{"id":6077,"date":"2019-12-15T12:21:07","date_gmt":"2019-12-15T11:21:07","guid":{"rendered":"https:\/\/relaunch.megabloc.de\/service\/reitplatzumrandung\/"},"modified":"2019-12-15T12:37:52","modified_gmt":"2019-12-15T11:37:52","slug":"bordure-de-maneges","status":"publish","type":"portfolio","link":"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/","title":{"rendered":"BORDURE DE MAN\u00c8GES"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Le bloc en b\u00e9ton MEGABLOC est utilis\u00e9e de plus en plus souvent comme bordure pour les man\u00e8ges. Sur les photos, vous voyez le bloc MEGABLOC type TOP comme cl\u00f4ture du terrain sabl\u00e9.\u00a0Dans les ouvertures au-dessus, un syst\u00e8me de palissade y a \u00e9t\u00e9 reli\u00e9.<\/p>\n<p>Vous trouverez ici d\u2019autres informations\u00a0:\u00a0<strong><a href=\"https:\/\/www.megabloc.de\/fr\/domaines-dutilisation-application\/manege\/\">MANEGES\u00a0 \/ CENTRES D\u2019EQUITATION<\/a><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_masonry_media_grid gap=\u00a0\u00bb20&Prime; item=\u00a0\u00bbmediaGrid_ScaleInWithIcon\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1576409375326-12873e5d-6331-2&Prime; include=\u00a0\u00bb4736,4667,5138,5582,5579&Prime;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le bloc en b\u00e9ton MEGABLOC est utilis\u00e9e de plus en plus souvent comme bordure pour les man\u00e8ges. Sur les photos, vous voyez le bloc MEGABLOC type TOP comme cl\u00f4ture du terrain sabl\u00e9. Dans les ouvertures au-dessus, un syst\u00e8me de palissade y a \u00e9t\u00e9 reli\u00e9.<\/p>\n","protected":false},"author":1,"featured_media":4730,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"portfolio-types":[120],"class_list":["post-6077","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-utilisations"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BORDURE DE MAN\u00c8GES - MEGABLOC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BORDURE DE MAN\u00c8GES - MEGABLOC\" \/>\n<meta property=\"og:description\" content=\"Le bloc en b\u00e9ton MEGABLOC est utilis\u00e9e de plus en plus souvent comme bordure pour les man\u00e8ges. Sur les photos, vous voyez le bloc MEGABLOC type TOP comme cl\u00f4ture du terrain sabl\u00e9. Dans les ouvertures au-dessus, un syst\u00e8me de palissade y a \u00e9t\u00e9 reli\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/\" \/>\n<meta property=\"og:site_name\" content=\"MEGABLOC\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-15T11:37:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.megabloc.de\/wp-content\/uploads\/2015\/04\/betonsteine-umrandung-sandplatzes-02.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1632\" \/>\n\t<meta property=\"og:image:height\" content=\"1224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/service\\\/bordure-de-maneges\\\/\",\"url\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/service\\\/bordure-de-maneges\\\/\",\"name\":\"BORDURE DE MAN\u00c8GES - MEGABLOC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/service\\\/bordure-de-maneges\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/service\\\/bordure-de-maneges\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.megabloc.de\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/betonsteine-umrandung-sandplatzes-02.jpeg\",\"datePublished\":\"2019-12-15T11:21:07+00:00\",\"dateModified\":\"2019-12-15T11:37:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/service\\\/bordure-de-maneges\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/service\\\/bordure-de-maneges\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/service\\\/bordure-de-maneges\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.megabloc.de\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/betonsteine-umrandung-sandplatzes-02.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.megabloc.de\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/betonsteine-umrandung-sandplatzes-02.jpeg\",\"width\":1632,\"height\":1224},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/service\\\/bordure-de-maneges\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BORDURE DE MAN\u00c8GES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/\",\"name\":\"MEGABLOC\",\"description\":\"BLOCS B\u00c9TON EMPILABLES: L'ORIGINAL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.megabloc.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BORDURE DE MAN\u00c8GES - MEGABLOC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/","og_locale":"fr_FR","og_type":"article","og_title":"BORDURE DE MAN\u00c8GES - MEGABLOC","og_description":"Le bloc en b\u00e9ton MEGABLOC est utilis\u00e9e de plus en plus souvent comme bordure pour les man\u00e8ges. Sur les photos, vous voyez le bloc MEGABLOC type TOP comme cl\u00f4ture du terrain sabl\u00e9. Dans les ouvertures au-dessus, un syst\u00e8me de palissade y a \u00e9t\u00e9 reli\u00e9.","og_url":"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/","og_site_name":"MEGABLOC","article_modified_time":"2019-12-15T11:37:52+00:00","og_image":[{"width":1632,"height":1224,"url":"https:\/\/www.megabloc.de\/wp-content\/uploads\/2015\/04\/betonsteine-umrandung-sandplatzes-02.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/","url":"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/","name":"BORDURE DE MAN\u00c8GES - MEGABLOC","isPartOf":{"@id":"https:\/\/www.megabloc.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/#primaryimage"},"image":{"@id":"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/#primaryimage"},"thumbnailUrl":"https:\/\/www.megabloc.de\/wp-content\/uploads\/2015\/04\/betonsteine-umrandung-sandplatzes-02.jpeg","datePublished":"2019-12-15T11:21:07+00:00","dateModified":"2019-12-15T11:37:52+00:00","breadcrumb":{"@id":"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/#primaryimage","url":"https:\/\/www.megabloc.de\/wp-content\/uploads\/2015\/04\/betonsteine-umrandung-sandplatzes-02.jpeg","contentUrl":"https:\/\/www.megabloc.de\/wp-content\/uploads\/2015\/04\/betonsteine-umrandung-sandplatzes-02.jpeg","width":1632,"height":1224},{"@type":"BreadcrumbList","@id":"https:\/\/www.megabloc.de\/fr\/service\/bordure-de-maneges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.megabloc.de\/fr\/"},{"@type":"ListItem","position":2,"name":"BORDURE DE MAN\u00c8GES"}]},{"@type":"WebSite","@id":"https:\/\/www.megabloc.de\/fr\/#website","url":"https:\/\/www.megabloc.de\/fr\/","name":"MEGABLOC","description":"BLOCS B\u00c9TON EMPILABLES: L'ORIGINAL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.megabloc.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.megabloc.de\/fr\/wp-json\/wp\/v2\/portfolio\/6077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.megabloc.de\/fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.megabloc.de\/fr\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.megabloc.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.megabloc.de\/fr\/wp-json\/wp\/v2\/comments?post=6077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.megabloc.de\/fr\/wp-json\/wp\/v2\/media\/4730"}],"wp:attachment":[{"href":"https:\/\/www.megabloc.de\/fr\/wp-json\/wp\/v2\/media?parent=6077"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/www.megabloc.de\/fr\/wp-json\/wp\/v2\/portfolio-types?post=6077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}