{"id":2641,"date":"2015-12-30T14:24:24","date_gmt":"2015-12-30T13:24:24","guid":{"rendered":"http:\/\/www.megabloc.de\/?page_id=2641"},"modified":"2015-12-30T14:24:24","modified_gmt":"2015-12-30T13:24:24","slug":"rampa-aiuto-trasferimento","status":"publish","type":"page","link":"https:\/\/www.megabloc.de\/it\/rampa-aiuto-trasferimento\/","title":{"rendered":"Rampa \/ aiuto trasferimento"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<div class=\"container-textbox4 wider\">\n<h2>Rampa \/ aiuto trasferimento<\/h2>\n<\/div>\n<p>Con le tonnellate dei blocchi MEGABLOC possono essere create rampe o stazioni di trasferimento in pochissimo tempo<strong>.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][vc_gallery type=&#8221;image_grid&#8221; interval=&#8221;3&#8243; images=&#8221;1190,1191&#8243; onclick=&#8221;link_image&#8221; custom_links_target=&#8221;_self&#8221; img_size=&#8221;300&#215;200&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Rampa \/ aiuto trasferimento Con le tonnellate dei blocchi MEGABLOC possono essere create rampe o stazioni di trasferimento in pochissimo tempo.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][vc_gallery type=&#8221;image_grid&#8221; interval=&#8221;3&#8243; images=&#8221;1190,1191&#8243;<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"page-templates\/page-default.php","meta":{"footnotes":""},"class_list":["post-2641","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rampa \/ aiuto trasferimento - Megabloc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.megabloc.de\/it\/rampa-aiuto-trasferimento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rampa \/ aiuto trasferimento - Megabloc\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] Rampa \/ aiuto trasferimento Con le tonnellate dei blocchi MEGABLOC possono essere create rampe o stazioni di trasferimento in pochissimo tempo.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][vc_gallery type=&#8221;image_grid&#8221; interval=&#8221;3&#8243; images=&#8221;1190,1191&#8243; [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.megabloc.de\/it\/rampa-aiuto-trasferimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Megabloc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/it\\\/rampa-aiuto-trasferimento\\\/\",\"url\":\"https:\\\/\\\/www.megabloc.de\\\/it\\\/rampa-aiuto-trasferimento\\\/\",\"name\":\"Rampa \\\/ aiuto trasferimento - Megabloc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/it\\\/#website\"},\"datePublished\":\"2015-12-30T13:24:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/it\\\/rampa-aiuto-trasferimento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.megabloc.de\\\/it\\\/rampa-aiuto-trasferimento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/it\\\/rampa-aiuto-trasferimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.megabloc.de\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rampa \\\/ aiuto trasferimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.megabloc.de\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.megabloc.de\\\/it\\\/\",\"name\":\"Megabloc\",\"description\":\"L\u2019ORIGINALE I BLOCCHI DI CALCESTRUZZO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.megabloc.de\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rampa \/ aiuto trasferimento - Megabloc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.megabloc.de\/it\/rampa-aiuto-trasferimento\/","og_locale":"it_IT","og_type":"article","og_title":"Rampa \/ aiuto trasferimento - Megabloc","og_description":"[vc_row][vc_column][vc_column_text] Rampa \/ aiuto trasferimento Con le tonnellate dei blocchi MEGABLOC possono essere create rampe o stazioni di trasferimento in pochissimo tempo.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][vc_gallery type=&#8221;image_grid&#8221; interval=&#8221;3&#8243; images=&#8221;1190,1191&#8243; [\u2026]","og_url":"https:\/\/www.megabloc.de\/it\/rampa-aiuto-trasferimento\/","og_site_name":"Megabloc","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.megabloc.de\/it\/rampa-aiuto-trasferimento\/","url":"https:\/\/www.megabloc.de\/it\/rampa-aiuto-trasferimento\/","name":"Rampa \/ aiuto trasferimento - Megabloc","isPartOf":{"@id":"https:\/\/www.megabloc.de\/it\/#website"},"datePublished":"2015-12-30T13:24:24+00:00","breadcrumb":{"@id":"https:\/\/www.megabloc.de\/it\/rampa-aiuto-trasferimento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.megabloc.de\/it\/rampa-aiuto-trasferimento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.megabloc.de\/it\/rampa-aiuto-trasferimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.megabloc.de\/it\/"},{"@type":"ListItem","position":2,"name":"Rampa \/ aiuto trasferimento"}]},{"@type":"WebSite","@id":"https:\/\/www.megabloc.de\/it\/#website","url":"https:\/\/www.megabloc.de\/it\/","name":"Megabloc","description":"L\u2019ORIGINALE I BLOCCHI DI CALCESTRUZZO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.megabloc.de\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.megabloc.de\/it\/wp-json\/wp\/v2\/pages\/2641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.megabloc.de\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.megabloc.de\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.megabloc.de\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.megabloc.de\/it\/wp-json\/wp\/v2\/comments?post=2641"}],"version-history":[{"count":1,"href":"https:\/\/www.megabloc.de\/it\/wp-json\/wp\/v2\/pages\/2641\/revisions"}],"predecessor-version":[{"id":2642,"href":"https:\/\/www.megabloc.de\/it\/wp-json\/wp\/v2\/pages\/2641\/revisions\/2642"}],"wp:attachment":[{"href":"https:\/\/www.megabloc.de\/it\/wp-json\/wp\/v2\/media?parent=2641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}